{"id":690,"date":"2018-12-18T18:35:50","date_gmt":"2018-12-18T17:35:50","guid":{"rendered":"http:\/\/polychrome-edu.fr\/?p=690"},"modified":"2018-12-18T18:40:59","modified_gmt":"2018-12-18T17:40:59","slug":"les-lyceens-des-quartiers-sud-de-grenoble-ont-ils-droit-a-lart","status":"publish","type":"post","link":"https:\/\/polychrome-edu.fr\/index.php\/2018\/12\/18\/les-lyceens-des-quartiers-sud-de-grenoble-ont-ils-droit-a-lart\/","title":{"rendered":"Les lyc\u00e9ens des quartiers sud de Grenoble ont-ils droit \u00e0 l&rsquo;art ?"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"690\" class=\"elementor elementor-690 elementor-bc-flex-widget\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-89976c6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"89976c6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-504533b\" data-id=\"504533b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b8e3bc6 elementor-widget elementor-widget-image\" data-id=\"b8e3bc6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"185\" src=\"https:\/\/polychrome-edu.fr\/wp-content\/uploads\/2018\/12\/Capture-d\u2019\u00e9cran-2018-12-18-\u00e0-15.04.24-300x185.png\" class=\"attachment-medium size-medium wp-image-670\" alt=\"\" srcset=\"https:\/\/polychrome-edu.fr\/wp-content\/uploads\/2018\/12\/Capture-d\u2019\u00e9cran-2018-12-18-\u00e0-15.04.24-300x185.png 300w, https:\/\/polychrome-edu.fr\/wp-content\/uploads\/2018\/12\/Capture-d\u2019\u00e9cran-2018-12-18-\u00e0-15.04.24.png 621w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-04ee1a9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"04ee1a9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-60a68e5\" data-id=\"60a68e5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ce47675 elementor-widget elementor-widget-heading\" data-id=\"ce47675\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><p style=\"margin-bottom: 0px;font-weight: normal;font-size: 12px;line-height: normal;font-family: Calibri;min-height: 14px\"><br><\/p>Lettre ouverte des enseignants du lyc\u00e9e Mounier de Grenoble<span style=\"font-size: 2.8rem;background-color: var(--mdc-theme-background,#fff)\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5a8bc69 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5a8bc69\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a346247\" data-id=\"a346247\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-493fc58 elementor-widget elementor-widget-text-editor\" data-id=\"493fc58\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"margin-bottom: 0px; font-stretch: normal; font-size: 12px; line-height: normal; font-family: Calibri; min-height: 14px;\">\u00a0<\/p><p style=\"margin-bottom: 0px; font-stretch: normal; font-size: 11.5px; line-height: normal; font-family: Calibri;\"><span style=\"font-stretch: normal; font-size: 12px; line-height: normal;\">\u00a0<\/span>Nous venons d&rsquo;apprendre qu&rsquo;au lyc\u00e9e Emmanuel Mounier de Grenoble, la sp\u00e9cialit\u00e9 Arts plastiques et l&rsquo;option Musique seront ferm\u00e9es \u00e0 la rentr\u00e9e 2019. Pour information, ces enseignements concernent au total 77 de nos \u00e9l\u00e8ves cette ann\u00e9e et permettent de valoriser les \u00e9l\u00e8ves du secteur dans des disciplines o\u00f9 peuvent exceller m\u00eame ceux qui ont des difficult\u00e9s avec la langue \u00e9crite et les enseignements plus scolaires. Les enseignants consid\u00e8rent donc cette d\u00e9cision scandaleuse, \u00e0 plus d&rsquo;un titre.\u00a0<\/p><p style=\"margin-bottom: 0px; font-stretch: normal; font-size: 11.5px; line-height: normal; font-family: Calibri;\">D&rsquo;une part elle montre bien que les possibilit\u00e9s de choix de nos lyc\u00e9ens en termes de sp\u00e9cialit\u00e9s vont \u00eatre appauvries et non \u00e9largies, contrairement \u00e0 l&rsquo;esprit de la r\u00e9forme du baccalaur\u00e9at. De ce fait nos \u00e9l\u00e8ves subiront une injustice flagrante, puisque ceux d&rsquo;autres lyc\u00e9es auront un choix plus large. Si la volont\u00e9 de mutualisation des sp\u00e9cialit\u00e9s est effective et coh\u00e9rente, ces sp\u00e9cialit\u00e9s pourraient tr\u00e8s bien \u00eatre ouvertes au lyc\u00e9e Mounier, qui va b\u00e9n\u00e9ficier dans quelques mois de locaux neufs et agrandis. En effet, des grands noms de l\u2019art contemporain sont issus de Mounier (par ex. Dominique Gonzalez-Foerster), et ces derni\u00e8res ann\u00e9es des \u00e9l\u00e8ves sont entr\u00e9s aux Arts-D\u00e9coratifs, aux Beaux-Arts, \u00e0 l&rsquo;Ecole du Louvre, aux Gobelins, ou en \u00e9coles de Cin\u00e9ma&#8230;. Ces \u00e9l\u00e8ves issus des classes populaires ont pu acc\u00e9der \u00e0 ces formations car la sp\u00e9cialit\u00e9 Arts Plastiques y existe et qu&rsquo;ils ont suivi assid\u00fbment l&rsquo;enseignement de sp\u00e9cialit\u00e9 associ\u00e9 \u00e0 l&rsquo;option facultative (soit 7h d&rsquo;enseignement par semaine). Etant souvent fragilis\u00e9s socialement, il sera difficile pour les \u00e9l\u00e8ves de Mounier d&rsquo;aller suivre ce seul enseignement dans un autre lyc\u00e9e. Au regard de l&rsquo;histoire de l&rsquo;art contemporain, c&rsquo;est \u00e0 Mounier qu&rsquo;il doit \u00eatre conserv\u00e9. Symboliquement, c&rsquo;est une \u00e9vidence. Les nouveaux locaux du lyc\u00e9e, qui sont en train d&rsquo;\u00eatre finalis\u00e9s sur le site, ont en leur sein 2 futures salles r\u00e9serv\u00e9es aux arts plastiques. Quel g\u00e2chis ce serait de ne pouvoir les faire vivre !\u00a0<\/p><p style=\"margin-bottom: 0px; font-stretch: normal; font-size: 11.5px; line-height: normal; font-family: Calibri;\">D&rsquo;autre part, cette d\u00e9cision nous inqui\u00e8te au plus haut point, car nous pensons qu&rsquo;elle va entra\u00eener une perte de mixit\u00e9 sociale et d&rsquo;h\u00e9t\u00e9rog\u00e9n\u00e9it\u00e9 scolaire, ce qui fait aujourd&rsquo;hui la force de notre \u00e9tablissement. Voulons-nous que Mounier devienne un lyc\u00e9e ghetto, alors m\u00eame que sa reconstruction permettrait d&rsquo;en faire un lyc\u00e9e pilote en termes de mixit\u00e9 et d&rsquo;ascension sociales et culturelles? Nous demandons donc que le lyc\u00e9e Mounier accueille au minimum, \u00e0 la rentr\u00e9e 2019, les sp\u00e9cialit\u00e9s et options arts plastiques, ainsi que l&rsquo;option musique, dans le respect de nos partenariats de longue date (MC2, Conservatoire) et de l&rsquo;engagement de l&rsquo;\u00e9quipe enseignante dans de nombreux projets artistiques et culturels (comme en t\u00e9moigne la fresque de Monkey Bird que chacun peut admirer depuis le tram).\u00a0<\/p><p style=\"margin-bottom: 0px; font-stretch: normal; font-size: 11.5px; line-height: normal; font-family: Calibri;\">Plus largement, nous pouvons nous interroger sur l&rsquo;avenir des autres sp\u00e9cialit\u00e9s, dans le contexte d&rsquo;une r\u00e9forme qui induit une r\u00e9duction de l&rsquo;offre p\u00e9dagogique pour vos enfants.\u00a0<\/p><p>\u00a0<\/p><p style=\"font-stretch: normal; font-size: 11.5px; line-height: normal; font-family: Calibri;\"><b><i>Les enseignants du lyc\u00e9e Mounier de Grenoble, le 14\/12\/2018\u00a0<\/i><\/b><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ba0b274 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ba0b274\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-aa12ff5\" data-id=\"aa12ff5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6e388fa elementor-widget elementor-widget-text-editor\" data-id=\"6e388fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00a0Pour en savoir plus sur la situation du lyc\u00e9e :<\/p><p>\u00a0<a href=\"https:\/\/www.lemonde.fr\/societe\/article\/2011\/01\/27\/a-grenoble-le-lycee-mounier-bloque-par-les-opposants-a-la-fermeture_1471128_3224.html\" target=\"_blank\" rel=\"noopener\">https:\/\/www.lemonde.fr\/societe\/article\/2011\/01\/27\/a-grenoble-le-lycee-mounier-bloque-par-les-opposants-a-la-fermeture_1471128_3224.html<\/a><\/p><p>Pour suivre le lyc\u00e9e Mounier sur sa pageFacebook et son fil twitter :\u00a0<\/p><p><a href=\"https:\/\/www.facebook.com\/collectifmounier2\/?modal=admin_todo_tour\" target=\"_blank\" rel=\"noopener\">https:\/\/www.facebook.com\/collectifmounier2\/?modal=admin_todo_tour<\/a><\/p><p><a href=\"https:\/\/twitter.com\/artpla5\/status\/1074139978932895744?s=21\" target=\"_blank\" rel=\"noopener\">https:\/\/twitter.com\/artpla5\/status\/1074139978932895744?s=21<\/a><\/p><p>Pour signer la p\u00e9tition :\u00a0<span style=\"font-family: ArialMT;\"><a href=\"https:\/\/secure.avaaz.org\/fr\/community_petitions\/Mme_La_Rectrice_de_Grenoble_Pour_le_maintien_de_la_specialite_Arts_plastiques_au_lycee_Emmanuel_Mounier\/?emMNbJnb&amp;utm_source=sharetools&amp;utm_medium=email&amp;utm_campaign=petition-624416-Mme_La_Rectrice_de_Grenoble_Pour_le_maintien_de_la_specialite_Arts_plastiques_au_lycee_Emmanuel_Mounier&amp;utm_term=MNbJnb%2Bfr\">https:\/\/secure.avaaz.org\/fr\/community_petitions\/Mme_La_Rectrice_de_Grenoble_Pour_le_maintien_de_la_specialite_Arts_plastiques_au_lycee_Emmanuel_Mounier\/?emMNbJnb&amp;utm_source=sharetools&amp;utm_medium=email&amp;utm_campaign=petition-624416-Mme_La_Rectrice_de_Grenoble_Pour_le_maintien_de_la_specialite_Arts_plastiques_au_lycee_Emmanuel_Mounier&amp;utm_term=MNbJnb%2Bfr<\/a><\/span><\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Lettre ouverte des enseignants du lyc\u00e9e Mounier de Grenoble \u00a0Nous venons d&rsquo;apprendre qu&rsquo;au lyc\u00e9e Emmanuel Mounier de Grenoble, la sp\u00e9cialit\u00e9 Arts plastiques et l&rsquo;option Musique seront ferm\u00e9es \u00e0 la rentr\u00e9e 2019. Pour information, ces enseignements concernent au total 77 de nos \u00e9l\u00e8ves cette ann\u00e9e et permettent de valoriser les \u00e9l\u00e8ves du secteur dans des disciplines&nbsp;&hellip;<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-690","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les lyc\u00e9ens des quartiers sud de Grenoble ont-ils droit \u00e0 l&#039;art ? - Polychrome-edu<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/polychrome-edu.fr\/index.php\/2018\/12\/18\/les-lyceens-des-quartiers-sud-de-grenoble-ont-ils-droit-a-lart\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les lyc\u00e9ens des quartiers sud de Grenoble ont-ils droit \u00e0 l&#039;art ? - Polychrome-edu\" \/>\n<meta property=\"og:description\" content=\"Lettre ouverte des enseignants du lyc\u00e9e Mounier de Grenoble \u00a0Nous venons d&rsquo;apprendre qu&rsquo;au lyc\u00e9e Emmanuel Mounier de Grenoble, la sp\u00e9cialit\u00e9 Arts plastiques et l&rsquo;option Musique seront ferm\u00e9es \u00e0 la rentr\u00e9e 2019. Pour information, ces enseignements concernent au total 77 de nos \u00e9l\u00e8ves cette ann\u00e9e et permettent de valoriser les \u00e9l\u00e8ves du secteur dans des disciplines&nbsp;&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/polychrome-edu.fr\/index.php\/2018\/12\/18\/les-lyceens-des-quartiers-sud-de-grenoble-ont-ils-droit-a-lart\/\" \/>\n<meta property=\"og:site_name\" content=\"Polychrome-edu\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Polychrome-edufr-200275759992220\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-18T17:35:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-12-18T17:40:59+00:00\" \/>\n<meta name=\"author\" content=\"Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/polychrome-edu.fr\\\/index.php\\\/2018\\\/12\\\/18\\\/les-lyceens-des-quartiers-sud-de-grenoble-ont-ils-droit-a-lart\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/polychrome-edu.fr\\\/index.php\\\/2018\\\/12\\\/18\\\/les-lyceens-des-quartiers-sud-de-grenoble-ont-ils-droit-a-lart\\\/\"},\"author\":{\"name\":\"Admin\",\"@id\":\"https:\\\/\\\/polychrome-edu.fr\\\/#\\\/schema\\\/person\\\/f35d9dff2e584b133d42e6ef978f7f9c\"},\"headline\":\"Les lyc\u00e9ens des quartiers sud de Grenoble ont-ils droit \u00e0 l&rsquo;art ?\",\"datePublished\":\"2018-12-18T17:35:50+00:00\",\"dateModified\":\"2018-12-18T17:40:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/polychrome-edu.fr\\\/index.php\\\/2018\\\/12\\\/18\\\/les-lyceens-des-quartiers-sud-de-grenoble-ont-ils-droit-a-lart\\\/\"},\"wordCount\":682,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/polychrome-edu.fr\\\/#organization\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/polychrome-edu.fr\\\/index.php\\\/2018\\\/12\\\/18\\\/les-lyceens-des-quartiers-sud-de-grenoble-ont-ils-droit-a-lart\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/polychrome-edu.fr\\\/index.php\\\/2018\\\/12\\\/18\\\/les-lyceens-des-quartiers-sud-de-grenoble-ont-ils-droit-a-lart\\\/\",\"url\":\"https:\\\/\\\/polychrome-edu.fr\\\/index.php\\\/2018\\\/12\\\/18\\\/les-lyceens-des-quartiers-sud-de-grenoble-ont-ils-droit-a-lart\\\/\",\"name\":\"Les lyc\u00e9ens des quartiers sud de Grenoble ont-ils droit \u00e0 l'art ? - Polychrome-edu\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/polychrome-edu.fr\\\/#website\"},\"datePublished\":\"2018-12-18T17:35:50+00:00\",\"dateModified\":\"2018-12-18T17:40:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/polychrome-edu.fr\\\/index.php\\\/2018\\\/12\\\/18\\\/les-lyceens-des-quartiers-sud-de-grenoble-ont-ils-droit-a-lart\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/polychrome-edu.fr\\\/index.php\\\/2018\\\/12\\\/18\\\/les-lyceens-des-quartiers-sud-de-grenoble-ont-ils-droit-a-lart\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/polychrome-edu.fr\\\/index.php\\\/2018\\\/12\\\/18\\\/les-lyceens-des-quartiers-sud-de-grenoble-ont-ils-droit-a-lart\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/polychrome-edu.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Non class\u00e9\",\"item\":\"https:\\\/\\\/polychrome-edu.fr\\\/index.php\\\/category\\\/non-classe\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Les lyc\u00e9ens des quartiers sud de Grenoble ont-ils droit \u00e0 l&rsquo;art ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/polychrome-edu.fr\\\/#website\",\"url\":\"https:\\\/\\\/polychrome-edu.fr\\\/\",\"name\":\"Polychrome-edu\",\"description\":\"L&#039;Association nationale des professeurs d&#039;arts plastiques\",\"publisher\":{\"@id\":\"https:\\\/\\\/polychrome-edu.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/polychrome-edu.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/polychrome-edu.fr\\\/#organization\",\"name\":\"Polychrome-edu\",\"url\":\"https:\\\/\\\/polychrome-edu.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/polychrome-edu.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/polychrome-edu.fr\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/cropped-LOGO-TEXTE-NOIR-e1540477061508.png\",\"contentUrl\":\"https:\\\/\\\/polychrome-edu.fr\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/cropped-LOGO-TEXTE-NOIR-e1540477061508.png\",\"width\":744,\"height\":347,\"caption\":\"Polychrome-edu\"},\"image\":{\"@id\":\"https:\\\/\\\/polychrome-edu.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Polychrome-edufr-200275759992220\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/polychrome-edu.fr\\\/#\\\/schema\\\/person\\\/f35d9dff2e584b133d42e6ef978f7f9c\",\"name\":\"Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8d2418e80cc241a373448058cbc1ecf8217f3fad2d33c7a204266035762934ad?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8d2418e80cc241a373448058cbc1ecf8217f3fad2d33c7a204266035762934ad?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8d2418e80cc241a373448058cbc1ecf8217f3fad2d33c7a204266035762934ad?s=96&d=mm&r=g\",\"caption\":\"Admin\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les lyc\u00e9ens des quartiers sud de Grenoble ont-ils droit \u00e0 l'art ? - Polychrome-edu","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/polychrome-edu.fr\/index.php\/2018\/12\/18\/les-lyceens-des-quartiers-sud-de-grenoble-ont-ils-droit-a-lart\/","og_locale":"fr_FR","og_type":"article","og_title":"Les lyc\u00e9ens des quartiers sud de Grenoble ont-ils droit \u00e0 l'art ? - Polychrome-edu","og_description":"Lettre ouverte des enseignants du lyc\u00e9e Mounier de Grenoble \u00a0Nous venons d&rsquo;apprendre qu&rsquo;au lyc\u00e9e Emmanuel Mounier de Grenoble, la sp\u00e9cialit\u00e9 Arts plastiques et l&rsquo;option Musique seront ferm\u00e9es \u00e0 la rentr\u00e9e 2019. Pour information, ces enseignements concernent au total 77 de nos \u00e9l\u00e8ves cette ann\u00e9e et permettent de valoriser les \u00e9l\u00e8ves du secteur dans des disciplines&nbsp;&hellip;","og_url":"https:\/\/polychrome-edu.fr\/index.php\/2018\/12\/18\/les-lyceens-des-quartiers-sud-de-grenoble-ont-ils-droit-a-lart\/","og_site_name":"Polychrome-edu","article_publisher":"https:\/\/www.facebook.com\/Polychrome-edufr-200275759992220\/","article_published_time":"2018-12-18T17:35:50+00:00","article_modified_time":"2018-12-18T17:40:59+00:00","author":"Admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Admin","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/polychrome-edu.fr\/index.php\/2018\/12\/18\/les-lyceens-des-quartiers-sud-de-grenoble-ont-ils-droit-a-lart\/#article","isPartOf":{"@id":"https:\/\/polychrome-edu.fr\/index.php\/2018\/12\/18\/les-lyceens-des-quartiers-sud-de-grenoble-ont-ils-droit-a-lart\/"},"author":{"name":"Admin","@id":"https:\/\/polychrome-edu.fr\/#\/schema\/person\/f35d9dff2e584b133d42e6ef978f7f9c"},"headline":"Les lyc\u00e9ens des quartiers sud de Grenoble ont-ils droit \u00e0 l&rsquo;art ?","datePublished":"2018-12-18T17:35:50+00:00","dateModified":"2018-12-18T17:40:59+00:00","mainEntityOfPage":{"@id":"https:\/\/polychrome-edu.fr\/index.php\/2018\/12\/18\/les-lyceens-des-quartiers-sud-de-grenoble-ont-ils-droit-a-lart\/"},"wordCount":682,"commentCount":0,"publisher":{"@id":"https:\/\/polychrome-edu.fr\/#organization"},"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/polychrome-edu.fr\/index.php\/2018\/12\/18\/les-lyceens-des-quartiers-sud-de-grenoble-ont-ils-droit-a-lart\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/polychrome-edu.fr\/index.php\/2018\/12\/18\/les-lyceens-des-quartiers-sud-de-grenoble-ont-ils-droit-a-lart\/","url":"https:\/\/polychrome-edu.fr\/index.php\/2018\/12\/18\/les-lyceens-des-quartiers-sud-de-grenoble-ont-ils-droit-a-lart\/","name":"Les lyc\u00e9ens des quartiers sud de Grenoble ont-ils droit \u00e0 l'art ? - Polychrome-edu","isPartOf":{"@id":"https:\/\/polychrome-edu.fr\/#website"},"datePublished":"2018-12-18T17:35:50+00:00","dateModified":"2018-12-18T17:40:59+00:00","breadcrumb":{"@id":"https:\/\/polychrome-edu.fr\/index.php\/2018\/12\/18\/les-lyceens-des-quartiers-sud-de-grenoble-ont-ils-droit-a-lart\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/polychrome-edu.fr\/index.php\/2018\/12\/18\/les-lyceens-des-quartiers-sud-de-grenoble-ont-ils-droit-a-lart\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/polychrome-edu.fr\/index.php\/2018\/12\/18\/les-lyceens-des-quartiers-sud-de-grenoble-ont-ils-droit-a-lart\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/polychrome-edu.fr\/"},{"@type":"ListItem","position":2,"name":"Non class\u00e9","item":"https:\/\/polychrome-edu.fr\/index.php\/category\/non-classe\/"},{"@type":"ListItem","position":3,"name":"Les lyc\u00e9ens des quartiers sud de Grenoble ont-ils droit \u00e0 l&rsquo;art ?"}]},{"@type":"WebSite","@id":"https:\/\/polychrome-edu.fr\/#website","url":"https:\/\/polychrome-edu.fr\/","name":"Polychrome-edu","description":"L&#039;Association nationale des professeurs d&#039;arts plastiques","publisher":{"@id":"https:\/\/polychrome-edu.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/polychrome-edu.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/polychrome-edu.fr\/#organization","name":"Polychrome-edu","url":"https:\/\/polychrome-edu.fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/polychrome-edu.fr\/#\/schema\/logo\/image\/","url":"https:\/\/polychrome-edu.fr\/wp-content\/uploads\/2018\/10\/cropped-LOGO-TEXTE-NOIR-e1540477061508.png","contentUrl":"https:\/\/polychrome-edu.fr\/wp-content\/uploads\/2018\/10\/cropped-LOGO-TEXTE-NOIR-e1540477061508.png","width":744,"height":347,"caption":"Polychrome-edu"},"image":{"@id":"https:\/\/polychrome-edu.fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Polychrome-edufr-200275759992220\/"]},{"@type":"Person","@id":"https:\/\/polychrome-edu.fr\/#\/schema\/person\/f35d9dff2e584b133d42e6ef978f7f9c","name":"Admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/8d2418e80cc241a373448058cbc1ecf8217f3fad2d33c7a204266035762934ad?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8d2418e80cc241a373448058cbc1ecf8217f3fad2d33c7a204266035762934ad?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8d2418e80cc241a373448058cbc1ecf8217f3fad2d33c7a204266035762934ad?s=96&d=mm&r=g","caption":"Admin"}}]}},"_links":{"self":[{"href":"https:\/\/polychrome-edu.fr\/index.php\/wp-json\/wp\/v2\/posts\/690","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/polychrome-edu.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/polychrome-edu.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/polychrome-edu.fr\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/polychrome-edu.fr\/index.php\/wp-json\/wp\/v2\/comments?post=690"}],"version-history":[{"count":3,"href":"https:\/\/polychrome-edu.fr\/index.php\/wp-json\/wp\/v2\/posts\/690\/revisions"}],"predecessor-version":[{"id":693,"href":"https:\/\/polychrome-edu.fr\/index.php\/wp-json\/wp\/v2\/posts\/690\/revisions\/693"}],"wp:attachment":[{"href":"https:\/\/polychrome-edu.fr\/index.php\/wp-json\/wp\/v2\/media?parent=690"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/polychrome-edu.fr\/index.php\/wp-json\/wp\/v2\/categories?post=690"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/polychrome-edu.fr\/index.php\/wp-json\/wp\/v2\/tags?post=690"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}